{"id":27774,"date":"2025-05-07T14:19:33","date_gmt":"2025-05-07T17:19:33","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27774"},"modified":"2025-05-08T15:58:13","modified_gmt":"2025-05-08T18:58:13","slug":"ex-vereador-de-80-anos-morre-apos-ser-atingido-por-coice-de-vaca","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/05\/07\/ex-vereador-de-80-anos-morre-apos-ser-atingido-por-coice-de-vaca\/","title":{"rendered":"Ex-vereador de 80 anos morre ap\u00f3s ser atingido por coice de vaca"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"360\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-19.png\" alt=\"\" class=\"wp-image-27775\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-19.png 540w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-19-300x200.png 300w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure>\n<\/div>\n\n\n<p>Um ex-vereador de Rafael Jambeiro, a 96 quil\u00f4metros de Feira de Santana, morreu na manh\u00e3 de ter\u00e7a-feira (6) ap\u00f3s ser atingido por um coice de vaca em uma fazenda no distrito de Argoim. As informa\u00e7\u00f5es s\u00e3o da TV Suba\u00e9, afiliada da Rede Bahia.<\/p>\n\n\n\n<p>Segundo familiares, Ant\u00f4nio Pereira de Oliveira Sobrinho, de 80 anos, ordenhava uma vaca no domingo (5) quando um balde caiu no ch\u00e3o. Quando ele tentava pegar o objeto, o animal se assustou e o atingiu no abd\u00f4men.<\/p>\n\n\n\n<p>O idoso foi socorrido e levado inicialmente ao Hospital Municipal de Rafael Jambeiro. Depois, transferido para o Hospital Geral Cl\u00e9riston Andrade (HGCA), em Feira de Santana. Ant\u00f4nio n\u00e3o resistiu aos ferimentos e morreu dois dias depois.<\/p>\n\n\n\n<p>Em nota, a prefeitura de Rafael Jambeiro lamentou a morte do ex-vereador, conhecido como \u201cT\u00f5e de Deco\u201d, destacando os servi\u00e7os prestados por ele \u00e0 comunidade. A gest\u00e3o municipal tamb\u00e9m se solidarizou com familiares e amigos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ex-vereador de Rafael Jambeiro, a 96 quil\u00f4metros de Feira de Santana, morreu na manh\u00e3 de ter\u00e7a-feira (6) ap\u00f3s ser atingido por um coice de vaca em uma fazenda no distrito de Argoim. As informa\u00e7\u00f5es s\u00e3o da TV Suba\u00e9, afiliada da Rede Bahia. Segundo familiares, Ant\u00f4nio Pereira de Oliveira Sobrinho, de 80 anos, ordenhava uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-27774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27774"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27774\/revisions"}],"predecessor-version":[{"id":27776,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27774\/revisions\/27776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27775"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}