{"id":6998,"date":"2021-07-16T14:39:00","date_gmt":"2021-07-16T17:39:00","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=6998"},"modified":"2021-07-21T07:21:16","modified_gmt":"2021-07-21T10:21:16","slug":"jovem-e-morto-a-tiros-em-queimadas-mae-chora-ao-lado-do-corpo-e-pede-justica","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2021\/07\/16\/jovem-e-morto-a-tiros-em-queimadas-mae-chora-ao-lado-do-corpo-e-pede-justica\/","title":{"rendered":"Jovem \u00e9 morto a tiros em Queimadas; m\u00e3e chora ao lado do corpo e pede Justi\u00e7a"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"431\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/07\/queimadas4881159_.jpg\" alt=\"\" class=\"wp-image-6999\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/07\/queimadas4881159_.jpg 540w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/07\/queimadas4881159_-300x239.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/07\/queimadas4881159_-526x420.jpg 526w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure><\/div>\n\n\n\n<p>Um jovem de 21 anos foi morto com tiros no povoado Jacurici da Ponte, em Queimadas (BA), na manh\u00e3 desta sexta-feira (16). De acordo com relatos de populares, Diogo Silva da Concei\u00e7\u00e3o de Fran\u00e7a estava em frente a sua resid\u00eancia quando foi surpreendido por homens armados que chegaram em um carro.<\/p>\n\n\n\n<p>Ainda de acordo com os relatos, o jovem saiu correndo, mas foi alcan\u00e7ado e alvejado no meio da rua. A v\u00edtima n\u00e3o resistiu aos ferimentos e morreu no local. Uma imagem mostra uma mulher chorando ao lado do corpo e pedindo respostas \u00e0 Justi\u00e7a. Segundo a Guarda Civil Municipal (GCM), trata-se da m\u00e3e da v\u00edtima.<\/p>\n\n\n\n<p>O caso ser\u00e1 investigado pela Pol\u00edcia Civil.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Via Not\u00edcias de Santaluz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um jovem de 21 anos foi morto com tiros no povoado Jacurici da Ponte, em Queimadas (BA), na manh\u00e3 desta sexta-feira (16). De acordo com relatos de populares, Diogo Silva da Concei\u00e7\u00e3o de Fran\u00e7a estava em frente a sua resid\u00eancia quando foi surpreendido por homens armados que chegaram em um carro. Ainda de acordo com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6999,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-6998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/6998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=6998"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/6998\/revisions"}],"predecessor-version":[{"id":7000,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/6998\/revisions\/7000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/6999"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=6998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=6998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=6998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}