{"id":7682,"date":"2021-10-08T16:58:33","date_gmt":"2021-10-08T19:58:33","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=7682"},"modified":"2021-10-14T18:59:54","modified_gmt":"2021-10-14T21:59:54","slug":"dono-de-motor-de-sisal-e-baleado-em-tentativa-de-assalto-em-conceicao-do-coite","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2021\/10\/08\/dono-de-motor-de-sisal-e-baleado-em-tentativa-de-assalto-em-conceicao-do-coite\/","title":{"rendered":"Dono de motor de sisal \u00e9 baleado em tentativa de assalto em Concei\u00e7\u00e3o do Coit\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"410\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/01\/viatura.jpg\" alt=\"\" class=\"wp-image-5519\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/01\/viatura.jpg 550w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/01\/viatura-300x224.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/01\/viatura-80x60.jpg 80w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/01\/viatura-265x198.jpg 265w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure><\/div>\n\n\n\n<p>Na tarde desta sexta-feira (8), um homem conhecido como Evandro, morador na comunidade de Balag\u00e3o, regi\u00e3o do distrito de Bandia\u00e7u, em Concei\u00e7\u00e3o do Coit\u00e9, deu entrada na emerg\u00eancia do Hospital Portugu\u00eas ap\u00f3s ser atingido com um disparo de arma de fogo.<\/p>\n\n\n\n<p>O Informe Bahia apurou que, Evandro \u00e9 dono do motor de sisal e foi em uma batedeira de sisal no distrito para receber dinheiro da venda da fibra para pagar os trabalhadores. Quando estava aguardando receber o dinheiro apareceu um indiv\u00edduo armado que anunciou o assalto e pedindo dinheiro, Evandro respondeu que ainda n\u00e3o tinha recebido.<\/p>\n\n\n\n<p>Em seguida o indiv\u00edduo tentou roubar o dono da batedeira que conseguir fechar a porta do escrit\u00f3rio, quando o suspeito efetuou um disparo de arma de fogo que atingiu o bra\u00e7o de Evandro, chegando a quebrar o membro. Devido a fratura a v\u00edtima foi transferida para Feira de Santana. <\/p>\n\n\n\n<p>A pol\u00edcia militar foi acionada e est\u00e1 fazendo buscas para prender o suspeito.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*IB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde desta sexta-feira (8), um homem conhecido como Evandro, morador na comunidade de Balag\u00e3o, regi\u00e3o do distrito de Bandia\u00e7u, em Concei\u00e7\u00e3o do Coit\u00e9, deu entrada na emerg\u00eancia do Hospital Portugu\u00eas ap\u00f3s ser atingido com um disparo de arma de fogo. O Informe Bahia apurou que, Evandro \u00e9 dono do motor de sisal e foi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-7682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=7682"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7682\/revisions"}],"predecessor-version":[{"id":7683,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7682\/revisions\/7683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/5519"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=7682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=7682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=7682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}