{"id":7876,"date":"2021-11-05T18:25:23","date_gmt":"2021-11-05T21:25:23","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=7876"},"modified":"2021-11-07T10:23:25","modified_gmt":"2021-11-07T13:23:25","slug":"marilia-mendonca-morre-em-queda-de-aviao-em-minas-gerais","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2021\/11\/05\/marilia-mendonca-morre-em-queda-de-aviao-em-minas-gerais\/","title":{"rendered":"Mar\u00edlia Mendon\u00e7a morre em queda de avi\u00e3o em Minas Gerais"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/G1.jpg\" alt=\"\" class=\"wp-image-7878\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/G1.jpg 500w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/G1-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<p>A cantora Mar\u00edlia Mendon\u00e7a, de 26 anos, e mais quatro pessoas morreram na tarde desta sexta-feira (5) ap\u00f3s a queda de um avi\u00e3o de pequeno porte perto de uma cachoeira na serra de Caratinga, interior de Minas Gerais.<\/p>\n\n\n\n<p>&#8220;Com imenso pesar, confirmamos a morte da cantora Mar\u00edlia Mendon\u00e7a, seu produtor Henrique Ribeiro, seu tio e assessor Abicieli Silveira Dias Filho, do piloto e copiloto do avi\u00e3o, os quais iremos preservar os nomes neste momento. O avi\u00e3o decolou de Goi\u00e2nia com destino a Caratinga\/MG, onde Mar\u00edlia teria uma apresenta\u00e7\u00e3o esta noite. De momento, s\u00e3o estas as informa\u00e7\u00f5es que temos.&#8221;, informou em nota a assessoria da cantora.<\/p>\n\n\n\n<p>Os bombeiros tamb\u00e9m confirmaram a morte atrav\u00e9s da seguinte nota: &#8220;O Corpo de Bombeiros Militar de Minas Gerais informa que nesta sexta (5), ocorreu a queda de uma aeronave de pequeno porte, modelo Beech Aircraft, na zona rural de Piedade de Caratinga. O CBMMG confirma que a aeronave transportava a cantora Mar\u00edlia Mendon\u00e7a e que ela est\u00e1 entre as v\u00edtimas fatais.&#8221;<\/p>\n\n\n\n<p>A cantora nasceu em Cristian\u00f3polis (GO) em 22 de julho de 1995. Ela surgiu como \u00edcone do \u201cfeminejo\u201d em 2016, com sucessos como \u201cInfiel\u201d e \u201cEu sei de cor\u201d. Antes, ela j\u00e1 era compositora de sucessos do sertanejo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/EM1.jpg\" alt=\"\" class=\"wp-image-7877\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/EM1.jpg 500w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2021\/11\/EM1-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption>foto: WhatsAapp\/Reprodu\u00e7\u00e3o<\/figcaption><\/figure><\/div>\n\n\n\n<p>A aeronave era um bimotor Beech Aircraft, da PEC T\u00e1xi A\u00e9reo, de Goi\u00e1s, prefixo PT-ONJ, com capacidade para seis passageiros. Segundo a Anac, o avi\u00e3o est\u00e1 em situa\u00e7\u00e3o regular e tem autoriza\u00e7\u00e3o para fazer t\u00e1xi a\u00e9reo.<\/p>\n\n\n\n<p>Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre o motivo da queda do avi\u00e3o. A Aeron\u00e1utica vai apurar as causas do acidente. Investigadores foram enviados para o local.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil de Minas Gerais tamb\u00e9m confirmou as mortes e disse que enviou equipes de per\u00edcia criminal, investigadores e delegados ao local.<\/p>\n\n\n\n<p>Antes de embarcar fez um v\u00eddeo em que aparecia entrando no avi\u00e3o e publicou no Twitter.<\/p>\n\n\n\n<p><strong>Informa\u00e7\u00f5es da assessoria de imprensa<\/strong><\/p>\n\n\n\n<p>Por volta das16h30, a assessora de imprensa de Mar\u00edlia Mendon\u00e7a informou ao g1 que a cantora e todos que estavam no avi\u00e3o j\u00e1 teriam sido resgatados e estavam bem. A assessora voltou a confirmar a informa\u00e7\u00e3o \u00e0s 16h50, mas, por volta das 17h15 disse que havia perdido o contato com o empres\u00e1rio da cantora e que n\u00e3o podia mais confirmar a informa\u00e7\u00e3o de que ela estava bem. \u00c0s 17h45, a assessoria informou em nota oficial que a cantora havia morrido.<\/p>\n\n\n\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cantora Mar\u00edlia Mendon\u00e7a, de 26 anos, e mais quatro pessoas morreram na tarde desta sexta-feira (5) ap\u00f3s a queda de um avi\u00e3o de pequeno porte perto de uma cachoeira na serra de Caratinga, interior de Minas Gerais. &#8220;Com imenso pesar, confirmamos a morte da cantora Mar\u00edlia Mendon\u00e7a, seu produtor Henrique Ribeiro, seu tio e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-7876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=7876"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7876\/revisions"}],"predecessor-version":[{"id":7879,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/7876\/revisions\/7879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/7878"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=7876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=7876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=7876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}